{"id":174,"date":"2023-04-28T10:59:30","date_gmt":"2023-04-28T10:59:30","guid":{"rendered":"https:\/\/theme-demos.pixahive.com\/ph-news-paper\/?p=174"},"modified":"2024-08-06T10:53:43","modified_gmt":"2024-08-06T13:53:43","slug":"donec-vestibulum-fringilla-tellus-sit-amet-vehicula","status":"publish","type":"post","link":"https:\/\/concurso-publico.com\/index.php\/2023\/04\/28\/donec-vestibulum-fringilla-tellus-sit-amet-vehicula\/","title":{"rendered":"Prefeitura de Taquarituba &#8211; SP lan\u00e7a Concurso P\u00fablico com 23 vagasVagas dispon\u00edveis para cargos em diversas \u00e1reas e n\u00edveis de escolaridade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No estado de S\u00e3o Paulo, a Prefeitura de Taquarituba divulgou o edital retificado do novo Concurso P\u00fablico, que visa a contrata\u00e7\u00e3o de profissionais para diversos cargos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os interessados poder\u00e3o se inscrever entre 24 de junho de 2024 e 7 de agosto de 2024, atrav\u00e9s do site do Instituto Unique, com taxas de inscri\u00e7\u00e3o de R$ 48,00 ou R$ 50,00, dependendo do n\u00edvel de escolaridade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A prorroga\u00e7\u00e3o do per\u00edodo de inscri\u00e7\u00e3o resultou em atualiza\u00e7\u00f5es no cronograma, incluindo a nova data para a realiza\u00e7\u00e3o das provas objetivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e3o dispon\u00edveis 23 vagas, al\u00e9m de forma\u00e7\u00e3o de cadastro reserva, para as seguintes fun\u00e7\u00f5es e n\u00edveis de escolaridade:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>N\u00edvel M\u00e9dio:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Educador\/Cuidador (5 vagas)<\/li>\n\n\n\n<li>Auxiliar de Educador\/Cuidador (16 vagas)<\/li>\n\n\n\n<li>Operador de M\u00e1quinas Rodovi\u00e1rias (1 vaga)<\/li>\n\n\n\n<li>Mec\u00e2nico (1 vaga)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>N\u00edvel T\u00e9cnico:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>T\u00e9cnico em Inform\u00e1tica<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>N\u00edvel Superior:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>T\u00e9cnico de Esportes<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Os profissionais contratados ter\u00e3o uma jornada de 40 horas semanais e receber\u00e3o sal\u00e1rios que variam entre R$ 1.925,18 e R$ 3.652,01.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Candidatos que atendem aos crit\u00e9rios do edital podem solicitar isen\u00e7\u00e3o da taxa de inscri\u00e7\u00e3o at\u00e9 31 de julho de 2024.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Classifica\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A sele\u00e7\u00e3o dos candidatos ser\u00e1 feita atrav\u00e9s de prova objetiva, com previs\u00e3o de aplica\u00e7\u00e3o para 1\u00ba de setembro de 2024. Para o cargo de T\u00e9cnico de Esportes, haver\u00e1 tamb\u00e9m an\u00e1lise de t\u00edtulos. Candidatos aos cargos de Operador de M\u00e1quinas Rodovi\u00e1rias e Mec\u00e2nico ser\u00e3o avaliados por meio de prova pr\u00e1tica, prevista para 15 de setembro de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A prova objetiva consistir\u00e1 em 40 quest\u00f5es de m\u00faltipla escolha, abordando conte\u00fados de conhecimentos espec\u00edficos, l\u00edngua portuguesa, matem\u00e1tica, e conhecimentos gerais e atualidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Validade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O Concurso P\u00fablico ter\u00e1 validade de dois anos a partir da data de homologa\u00e7\u00e3o do resultado final, com possibilidade de prorroga\u00e7\u00e3o por igual per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais detalhes e o edital completo est\u00e3o dispon\u00edveis no site abaixo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/portal.unique.selecao.site\/edital\/ver\/65\" target=\"_blank\" rel=\"noopener\">https:\/\/portal.unique.selecao.site\/edital\/ver\/65<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No estado de S\u00e3o Paulo, a Prefeitura de Taquarituba divulgou o edital retificado do novo Concurso P\u00fablico, que visa a contrata\u00e7\u00e3o de profissionais para diversos cargos. Os interessados poder\u00e3o se&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,30],"tags":[],"class_list":["post-174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-Concurso-Sudeste","category-sao-paulo"],"_links":{"self":[{"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/posts\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":3,"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/posts\/174\/revisions"}],"predecessor-version":[{"id":282,"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/posts\/174\/revisions\/282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/media\/280"}],"wp:attachment":[{"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/media?parent=174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/categories?post=174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/concurso-publico.com\/index.php\/wp-json\/wp\/v2\/tags?post=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}